{"id":6416,"date":"2024-01-29T10:49:46","date_gmt":"2024-01-29T14:49:46","guid":{"rendered":"https:\/\/globalpartners.cl\/?page_id=6416"},"modified":"2026-03-18T11:46:49","modified_gmt":"2026-03-18T15:46:49","slug":"home","status":"publish","type":"page","link":"https:\/\/globalpartners.cl\/en\/","title":{"rendered":"Home"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6416\" class=\"elementor elementor-6416\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5ccdfc2 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"5ccdfc2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/globalpartners.cl\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/globalpartners.cl_1web.mp4&quot;,&quot;background_play_on_mobile&quot;:&quot;yes&quot;,&quot;background_video_start&quot;:0,&quot;_ha_eqh_enable&quot;:false}\" data-mobile-video=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/10\/Home-2.mp4\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-background-video-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<video class=\"elementor-background-video-hosted\" role=\"presentation\" autoplay muted playsinline loop><\/video>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-b757574\" data-id=\"b757574\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-1b5c489\" data-id=\"1b5c489\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cccc131 animated-fast elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"cccc131\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Proteger la vida y salud de los trabajadores<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93e5747 animated-fast elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"93e5747\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInDown&quot;,&quot;_animation_mobile&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">es nuestro prop\u00f3sito<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-087aec1\" data-id=\"087aec1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4e03ccf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4e03ccf\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9593295\" data-id=\"9593295\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30f84c5 elementor-widget elementor-widget-html\" data-id=\"30f84c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"wrapper\">\r\n  <div id=\"wrapper-inner\">\r\n<div id=\"scroll-down\">\r\n  <span id=\"scroll-title\">\r\n    Desliza\r\n  <\/span>\r\n<\/div>\r\n  <\/div>\r\n  <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-11617bb elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"11617bb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a9cf49d\" data-id=\"a9cf49d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b7b7be5 elementor-widget elementor-widget-menu-anchor\" data-id=\"b7b7be5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"clientes\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11d2fcc elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"11d2fcc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">NUESTROS CLIENTES<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-45ca183 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"45ca183\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cf5717b\" data-id=\"cf5717b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d4caf3a elementor-widget elementor-widget-image-carousel\" data-id=\"d4caf3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;7&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;speed&quot;:1500,&quot;slides_to_show_tablet&quot;:&quot;4&quot;,&quot;slides_to_show_mobile&quot;:&quot;3&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:1000,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:80,&quot;sizes&quot;:[]},&quot;lazyload&quot;:&quot;yes&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel de im\u00e1genes\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 32\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/05\/AES-300x300.webp\" alt=\"AES\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 32\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/05\/am-300x300.webp\" alt=\"Antofagasta Minerals\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 32\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/05\/Anglo-American-300x300.webp\" alt=\"AngloAmerican\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 32\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/05\/bechtel-300x300.webp\" alt=\"BECHTEL\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 32\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/05\/Btg-300x300.webp\" alt=\"BTG Pactual\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 32\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/05\/cap-mineria-300x300.webp\" alt=\"CAP Miner\u00eda\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 de 32\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/05\/Copec-300x300.webp\" alt=\"Copec\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 de 32\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/05\/Crawford-300x300.webp\" alt=\"Crawford\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 de 32\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/05\/EMIN-300x300.webp\" alt=\"EMIN\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 de 32\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/05\/Enaex-300x300.webp\" alt=\"Enaex\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 de 32\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/05\/Excon-300x300.webp\" alt=\"Excon\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 de 32\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/05\/FlSmidth_Logo-300x300.webp\" alt=\"FLSmidth\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 de 32\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/05\/GNL-Quintero-300x300.webp\" alt=\"GNL Quintero\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 de 32\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/05\/GS-300x300.webp\" alt=\"Grupo Security\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 de 32\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/05\/latam-300x300.webp\" alt=\"LATAM\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"16 de 32\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/05\/logo-casablanca-300x300.webp\" alt=\"Transportes Casablanca\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"17 de 32\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/05\/Metso-300x300.webp\" alt=\"Metso\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"18 de 32\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/05\/Moller-y-Perez-Cotapos-300x300.webp\" alt=\"Moller &amp; Perez Cotapos\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"19 de 32\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/05\/Molycop-300x300.webp\" alt=\"Molycop\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"20 de 32\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/05\/Moneda-300x300.webp\" alt=\"Moneda\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"21 de 32\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/05\/Nazar-300x300.webp\" alt=\"Nazar\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"22 de 32\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/05\/NexusLogistics-300x300.webp\" alt=\"Nexus Logistics\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"23 de 32\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/05\/Rockwood-Lithium-copia-300x300.webp\" alt=\"Rockwood Lithium\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"24 de 32\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/05\/SKY-300x300.webp\" alt=\"SKY\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"25 de 32\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/05\/Sodimac-300x300.webp\" alt=\"SODIMAC\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"26 de 32\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/05\/Sonacol-300x300.webp\" alt=\"Sonacol\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"27 de 32\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/05\/SQM-300x300.webp\" alt=\"SQM\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"28 de 32\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/05\/TPS-Valparaiso-300x300.webp\" alt=\"TPS Valpara\u00edso\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"29 de 32\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/05\/Ultramar-300x300.webp\" alt=\"Ultramar\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"30 de 32\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/05\/Ultraport-300x300.webp\" alt=\"Ultraport\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"31 de 32\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/05\/Unodc-300x300.webp\" alt=\"UNODC\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"32 de 32\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/05\/WEIR-300x300.webp\" alt=\"WEIR Minerals\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-672132c elementor-align-center btn__verMas__testimonios elementor-invisible elementor-widget elementor-widget-button\" data-id=\"672132c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/globalpartners.cl\/#contacto\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SE PARTE DE GLOBAL PARTNERS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10517c8 elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-spacer\" data-id=\"10517c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b070add elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b070add\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c5addfb\" data-id=\"c5addfb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8539f5f elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"8539f5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-weight:500;font-size:28px\">DIVISI\u00d3N<\/span><br><span style=\"color: #E40520;font-size:30px\">ALCOHOL Y DROGAS<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fdffc05 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"fdffc05\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-5914356\" data-id=\"5914356\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-81ebeb0 elementor-flip-box--effect-fade elementor-widget elementor-widget-flip-box\" data-id=\"81ebeb0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper elementor-view-stacked elementor-shape-circle\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t\t\t<i class=\"hm hm-badge1\"><\/i>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\tPrograma Drug Free <br>Workplace\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\t\t<div class=\"caja_servicios\">\n<p>El programa DFWP es un aporte metodol\u00f3gico para que las empresas puedan abordar con \u00e9xito la problem\u00e1tica del consumo de alcohol y drogas en ambientes laborales.<\/p>\n\n<a class=\"link_caja_servicios\" href=\"https:\/\/drugfreeworkplace.cl\/\" rel=\"nofollow noopener\" target=\"_blank\">SABER M\u00c1S ><\/a>\n<img decoding=\"async\" src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2025\/04\/LOGO-BUEREAU-VERITAS-ACTUAL-copia.png\" width=\"150px\" height=\"auto\" alt=\"- GLOBAL PARTNERS\" title=\"- GLOBAL PARTNERS\">\n<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__back\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\t<ul>\n<li>Dise\u00f1o de pol\u00edtica de prevenci\u00f3n del consumo de A&D.<\/li>\n<li>Comunicaci\u00f3n, sensibilizaci\u00f3n y adhesi\u00f3n a la pol\u00edtica de A&D.<\/li>\n<li>Capacitaci\u00f3n en prevenci\u00f3n del consumo de A&D. <\/li>\n<li>Programa de ayuda al trabajador (PAT).<\/li>\n<li>Testeo del consumo de A&D.<\/li>\n<\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-flip-box__button elementor-button elementor-size-sm\" href=\"https:\/\/drugfreeworkplace.cl\/\" rel=\"nofollow noopener\" target=\"_blank\">\n\t\t\t\t\t\t\tExplorar\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-3467d7b\" data-id=\"3467d7b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-147c1e1 elementor-flip-box--effect-fade elementor-widget elementor-widget-flip-box\" data-id=\"147c1e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper elementor-view-stacked elementor-shape-circle\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t\t\t<i class=\"hm hm-server-network\"><\/i>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\tServicio de testeo de alcohol y drogas\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\t\t<div class=\"caja_servicios\">\n<p>Nuestro servicio de testeo utiliza tecnolog\u00eda de punta en pro de la confiabilidad, seguridad y privacidad de los resultados.<\/p>\n\n<a class=\"link_caja_servicios\" href=\"https:\/\/examendedrogas.cl\/\" rel=\"nofollow noopener\" target=\"_blank\">SABER M\u00c1S ><\/a>\n<img decoding=\"async\" src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2025\/04\/LOGO-BUEREAU-VERITAS-ACTUAL-copia.png\" width=\"150px\" height=\"auto\" alt=\"- GLOBAL PARTNERS\" title=\"- GLOBAL PARTNERS\">\n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__back\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\t<ul>\n <li>Acreditaci\u00f3n biom\u00e9trica.<\/li>\n <li>Resultados inmediatos.<\/li>\n <li>Altos est\u00e1ndares de seguridad.<\/li>\n <li>Informes estad\u00edsticos.<\/li>\n<\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-flip-box__button elementor-button elementor-size-sm\" href=\"https:\/\/examendedrogas.cl\/\" rel=\"nofollow noopener\" target=\"_blank\">\n\t\t\t\t\t\t\tExplorar\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-a059846\" data-id=\"a059846\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a9a47e3 elementor-flip-box--effect-fade elementor-widget elementor-widget-flip-box\" data-id=\"a9a47e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper elementor-view-stacked elementor-shape-circle\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t\t\t<i class=\"hm hm-dropper\"><\/i>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\tDispositivos de control de alcohol y drogas\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\t\t<div class=\"caja_servicios\">\n<p>Con nuestra gama de productos usted podr\u00e1 controlar el consumo de A&D en su organizaci\u00f3n.<\/p>\n\n<a class=\"link_caja_servicios\" href=\"https:\/\/testdealcoholydrogas.cl\/\" rel=\"nofollow noopener\" target=\"_blank\">SABER M\u00c1S ><\/a>\n<img decoding=\"async\" class=\"d-none\" src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/12\/LOGO-9001-2015.webp\" width=\"150px\" height=\"auto\" alt=\"- GLOBAL PARTNERS\" title=\"- GLOBAL PARTNERS\">\n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__back\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\t<ul>\n <li>Cat\u00e1logo de productos certificados para la detecci\u00f3n de A&D.<\/li>\n <li>Asistencia t\u00e9cnica para el uso de dispositivos.<\/li>\n <li>Agendamiento de asesor\u00eda personalizada.<\/li>\n <li>Servicio t\u00e9cnico de dispositivos.<\/li>\n<\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-flip-box__button elementor-button elementor-size-sm\" href=\"https:\/\/testdealcoholydrogas.cl\/\" rel=\"nofollow noopener\" target=\"_blank\">\n\t\t\t\t\t\t\tExplorar\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-23c6fb2\" data-id=\"23c6fb2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ed8fc86 elementor-flip-box--effect-fade elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-flip-box\" data-id=\"ed8fc86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper elementor-view-stacked elementor-shape-circle\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t\t\t<i class=\"hm hm-dropper\"><\/i>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\tServicio de calibraci\u00f3n y mantenci\u00f3n de equipos\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\t\t\u00danico autorizado en Chile, por nuestras marcas, para realizar calibraciones y mantenciones de alcotest y analizadores de drogas.\n<br\/>\n<br\/>\n<br\/>\n<a class=\"link_caja_servicios\" target=\"blank\" href=\"https:\/\/testdealcoholydrogas.cl\/servicio-tecnico\" rel=\"nofollow noopener\">SABER M\u00c1S ><\/a>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__back\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\t<ul>\n <li>Realizamos la calibraci\u00f3n o mantenci\u00f3n en 48 horas.<\/li>\n<li>Permite obtener resultados con la precisi\u00f3n dise\u00f1ada.<\/li>\n    <li>Fabricantes definen periodos de calibraci\u00f3n espec\u00edficos.<\/li>\n    <li>Asegura la confiabilidad de los resultados.<\/li>\n    <li>Prolonga la vida \u00fatil de los dispositivos.<\/li>\n<\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-flip-box__button elementor-button elementor-size-sm\" href=\"https:\/\/testdealcoholydrogas.cl\/servicio-tecnico\" rel=\"nofollow noopener\" target=\"_blank\">\n\t\t\t\t\t\t\tExplorar\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-97d0247 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"97d0247\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eda3daf\" data-id=\"eda3daf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-992ce5c elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"992ce5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-weight:500;font-size:28px\">DIVISI\u00d3N<\/span><br><span style=\"color: #E40520;font-size:30px\">MEDICINA LABORAL<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1f60c6a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1f60c6a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-da78029\" data-id=\"da78029\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d7674aa elementor-flip-box--effect-fade elementor-widget elementor-widget-flip-box\" data-id=\"d7674aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper elementor-view-stacked elementor-shape-circle\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t\t\t<i class=\"hm hm-corona-covid1\"><\/i>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\tServicio de testeo PCR Covid-19\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\t\tEl protocolo de testeo PCR Covid-19 permite detectar oportunamente el contagio por el virus SARS-CoV-2.\n<br\/>\n<br\/>\n<br\/>\n<a class=\"link_caja_servicios\" href=\"https:\/\/exameneslaborales.cl\/\" rel=\"nofollow noopener\" target=\"_blank\">SABER M\u00c1S ><\/a>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__back\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\t<ul>\n <li>Laboratorio de ana\u0301lisis - Red de Salud UC-CHRISTUS.<\/li>\n <li>Resultados entregados en 24 horas al encargado designado por la empresa contratante.<\/li>\n <li>M\u00e9dico contralor valida los resultados y firma el informe de recomendaciones finales.<\/li>\n<\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-flip-box__button elementor-button elementor-size-sm\" href=\"https:\/\/exameneslaborales.cl\/\" rel=\"nofollow noopener\" target=\"_blank\">\n\t\t\t\t\t\t\tExplorar\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-4a71007\" data-id=\"4a71007\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44a1fa7 elementor-flip-box--effect-fade elementor-widget elementor-widget-flip-box\" data-id=\"44a1fa7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper elementor-view-stacked elementor-shape-circle\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t\t\t<i class=\"hm hm-corona-covid1\"><\/i>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\tServicio de testeo ant\u00edgeno Covid-19\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\t\tEl protocolo de testeo ant\u00edgeno Covid-19 detecta oportunamente el contagio por el virus SARS-COV2, permitiendo adem\u00e1s la trazabilidad del contagio.\n<br\/>\n<br\/>\n<a class=\"link_caja_servicios\" href=\"https:\/\/exameneslaborales.cl\/\" rel=\"nofollow noopener\" target=\"_blank\">SABER M\u00c1S ><\/a>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__back\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\t<ul>\n <li>Dispositivos cuentan con autorizaci\u00f3n de uso de emergencia.<\/li>\n <li>Resultados inmediatos al trabajador y al encargado designado por la empresa contratante.<\/li>\n <li>M\u00e9dico contralor valida los resultados y firma el informe de recomendaciones finales.<\/li>\n<\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-flip-box__button elementor-button elementor-size-sm\" href=\"https:\/\/exameneslaborales.cl\/\" rel=\"nofollow noopener\" target=\"_blank\">\n\t\t\t\t\t\t\tExplorar\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-1253f74 elementor-hidden-mobile\" data-id=\"1253f74\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-19da7df elementor-hidden-mobile\" data-id=\"19da7df\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-95a2b54 elementor-section-stretched elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"95a2b54\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b8ccb4d\" data-id=\"b8ccb4d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-801a5a9 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"801a5a9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-fe93dc4\" data-id=\"fe93dc4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69dc999 elementor-align-center elementor-widget elementor-widget-lottie\" data-id=\"69dc999\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;source_json&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/globalpartners.cl\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/wired-outline-955-demand.json&quot;,&quot;id&quot;:6214,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;},&quot;trigger&quot;:&quot;none&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;source&quot;:&quot;media_file&quot;,&quot;caption_source&quot;:&quot;none&quot;,&quot;link_to&quot;:&quot;none&quot;,&quot;play_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;start_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;end_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:100,&quot;sizes&quot;:[]},&quot;renderer&quot;:&quot;svg&quot;}\" data-widget_type=\"lottie.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"e-lottie__container\"><div class=\"e-lottie__animation\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cecbba6 e-transform elementor-widget elementor-widget-counter\" data-id=\"cecbba6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.1,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<h2 class=\"elementor-counter-title\">TRABAJADORES TESTEADOS<\/h2>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\">+<\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2500\" data-to-value=\"200\" data-from-value=\"0\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">K<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-746fcd7\" data-id=\"746fcd7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-92450e9 elementor-align-center elementor-widget elementor-widget-lottie\" data-id=\"92450e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;source_json&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/globalpartners.cl\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/wired-outline-966-privacy-policy.json&quot;,&quot;id&quot;:6216,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;},&quot;trigger&quot;:&quot;none&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;source&quot;:&quot;media_file&quot;,&quot;caption_source&quot;:&quot;none&quot;,&quot;link_to&quot;:&quot;none&quot;,&quot;play_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;start_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;end_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:100,&quot;sizes&quot;:[]},&quot;renderer&quot;:&quot;svg&quot;}\" data-widget_type=\"lottie.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"e-lottie__container\"><div class=\"e-lottie__animation\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-894f0c6 e-transform elementor-widget elementor-widget-counter\" data-id=\"894f0c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.1,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<h2 class=\"elementor-counter-title\">PROGRAMAS DFWP IMPLEMENTADOS<\/h2>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\">+<\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2500\" data-to-value=\"30\" data-from-value=\"0\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-b8904c8\" data-id=\"b8904c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43afd6d elementor-align-center elementor-widget elementor-widget-lottie\" data-id=\"43afd6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;source_json&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/globalpartners.cl\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/wired-outline-28-calendar.json&quot;,&quot;id&quot;:6220,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;},&quot;trigger&quot;:&quot;none&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;source&quot;:&quot;media_file&quot;,&quot;caption_source&quot;:&quot;none&quot;,&quot;link_to&quot;:&quot;none&quot;,&quot;play_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;start_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;end_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:100,&quot;sizes&quot;:[]},&quot;renderer&quot;:&quot;svg&quot;}\" data-widget_type=\"lottie.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"e-lottie__container\"><div class=\"e-lottie__animation\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6a48fe e-transform elementor-widget elementor-widget-counter\" data-id=\"c6a48fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.1,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<h2 class=\"elementor-counter-title\">A\u00d1OS DE <br>EXPERIENCIA<\/h2>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2500\" data-to-value=\"22\" data-from-value=\"0\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-1e011ac\" data-id=\"1e011ac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2851d0e elementor-align-center elementor-widget elementor-widget-lottie\" data-id=\"2851d0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;source_json&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/globalpartners.cl\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/wired-outline-1274-digital-thermometer.json&quot;,&quot;id&quot;:6224,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;},&quot;trigger&quot;:&quot;none&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;source&quot;:&quot;media_file&quot;,&quot;caption_source&quot;:&quot;none&quot;,&quot;link_to&quot;:&quot;none&quot;,&quot;play_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;start_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;end_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:100,&quot;sizes&quot;:[]},&quot;renderer&quot;:&quot;svg&quot;}\" data-widget_type=\"lottie.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"e-lottie__container\"><div class=\"e-lottie__animation\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13b1759 e-transform elementor-widget elementor-widget-counter\" data-id=\"13b1759\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.1,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<h2 class=\"elementor-counter-title\">DISPOSITIVOS COMERCIALIZADOS<\/h2>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\">+<\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2500\" data-to-value=\"900\" data-from-value=\"0\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">K<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-91c21c4 elementor-align-center btn__verMas__testimonios elementor-invisible elementor-widget elementor-widget-button\" data-id=\"91c21c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/globalpartners.cl\/#contacto\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-envelope\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">CONT\u00c1CTANOS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0ea1c04 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"0ea1c04\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-930ed0a\" data-id=\"930ed0a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0e94d75 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0e94d75\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3737625\" data-id=\"3737625\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ddf5a28 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"ddf5a28\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-weight:500;font-size:28px\">TESTIMONIOS<\/span><br><span style=\"color: #E40520;font-size:30px\">CLIENTES<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-077a308 elementor-widget elementor-widget-menu-anchor\" data-id=\"077a308\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"testimonios\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fd55f4f elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"fd55f4f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0de9a73 elementor-invisible\" data-id=\"0de9a73\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJ0eXBlIjoidmlkZW8iLCJ2aWRlb1R5cGUiOiJ5b3V0dWJlIiwidXJsIjoiaHR0cHM6XC9cL3d3dy55b3V0dWJlLmNvbVwvZW1iZWRcLzM2UUwxR3ExNUpZP2ZlYXR1cmU9b2VtYmVkIn0%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-element elementor-element-369601b caja__testimonios elementor-widget elementor-widget-ha-image-hover-effect happy-addon ha-image-hover-effect\" data-id=\"369601b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ha-image-hover-effect.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ha-ihe-wrapper grid\">\n\t\t\t<figure class=\"ha-ihe-fig ha-effect-bubba\">\n\t\t\t\t<img decoding=\"async\" class=\"ha-ihe-img\" src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/06\/Captura-de-Pantalla-2022-06-20-a-las-11.28.06-copia.webp\" alt=\"Image hover effect image\" title=\"- GLOBAL PARTNERS\">\n\t\t\t\t<figcaption class=\"ha-ihe-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"ha-ihe-title\"><\/h2>\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"ha-ihe-desc\">Transportes <span>Casablanca<\/span>\n<\/br><i class=\"fas fa-play\"><\/i><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJ0eXBlIjoidmlkZW8iLCJ2aWRlb1R5cGUiOiJ5b3V0dWJlIiwidXJsIjoiaHR0cHM6XC9cL3d3dy55b3V0dWJlLmNvbVwvZW1iZWRcL3V3eVc2dFRHZ1NRP2ZlYXR1cmU9b2VtYmVkIn0%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-element elementor-element-5a26a79 caja__testimonios elementor-widget elementor-widget-ha-image-hover-effect happy-addon ha-image-hover-effect\" data-id=\"5a26a79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ha-image-hover-effect.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ha-ihe-wrapper grid\">\n\t\t\t<figure class=\"ha-ihe-fig ha-effect-bubba\">\n\t\t\t\t<img decoding=\"async\" class=\"ha-ihe-img\" src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/06\/Captura-de-Pantalla-2022-06-20-a-las-11.17.28-copia.webp\" alt=\"Image hover effect image\" title=\"- GLOBAL PARTNERS\">\n\t\t\t\t<figcaption class=\"ha-ihe-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"ha-ihe-title\"><\/h2>\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"ha-ihe-desc\">Nexus <span>Logistics<\/span>\n<\/br><i class=\"fas fa-play\"><\/i><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-702dc1d elementor-invisible\" data-id=\"702dc1d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJ0eXBlIjoidmlkZW8iLCJ2aWRlb1R5cGUiOiJ5b3V0dWJlIiwidXJsIjoiaHR0cHM6XC9cL3d3dy55b3V0dWJlLmNvbVwvZW1iZWRcLzI1WEtCMUcwbTdVP2ZlYXR1cmU9b2VtYmVkIn0%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-element elementor-element-7d216c6 caja__testimonios elementor-widget elementor-widget-ha-image-hover-effect happy-addon ha-image-hover-effect\" data-id=\"7d216c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ha-image-hover-effect.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ha-ihe-wrapper grid\">\n\t\t\t<figure class=\"ha-ihe-fig ha-effect-bubba\">\n\t\t\t\t<img decoding=\"async\" class=\"ha-ihe-img\" src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/06\/Captura-de-Pantalla-2022-06-20-a-las-11.23.20-copia-1.webp\" alt=\"Image hover effect image\" title=\"- GLOBAL PARTNERS\">\n\t\t\t\t<figcaption class=\"ha-ihe-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"ha-ihe-title\"><\/h2>\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"ha-ihe-desc\">Vulco Weir <span>Minerals<\/span>\n<\/br><i class=\"fas fa-play\"><\/i><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJ0eXBlIjoidmlkZW8iLCJ2aWRlb1R5cGUiOiJ5b3V0dWJlIiwidXJsIjoiaHR0cHM6XC9cL3d3dy55b3V0dWJlLmNvbVwvZW1iZWRcL0FLNGRKVXFrMTE0P2ZlYXR1cmU9b2VtYmVkIn0%3D&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-element elementor-element-e8a8531 caja__testimonios elementor-widget elementor-widget-ha-image-hover-effect happy-addon ha-image-hover-effect\" data-id=\"e8a8531\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ha-image-hover-effect.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ha-ihe-wrapper grid\">\n\t\t\t<figure class=\"ha-ihe-fig ha-effect-bubba\">\n\t\t\t\t<img decoding=\"async\" class=\"ha-ihe-img\" src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/06\/Captura-de-Pantalla-2022-06-20-a-las-11.08.43-copia.webp\" alt=\"Image hover effect image\" title=\"- GLOBAL PARTNERS\">\n\t\t\t\t<figcaption class=\"ha-ihe-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"ha-ihe-title\"><\/h2>\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"ha-ihe-desc\">Agro<span>commerce<\/span>\n<\/br><i class=\"fas fa-play\"><\/i><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-59ec62d elementor-widget elementor-widget-spacer\" data-id=\"59ec62d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2993532 elementor-align-center btn__verMas__testimonios elementor-invisible elementor-widget elementor-widget-button\" data-id=\"2993532\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.youtube.com\/c\/globalpartners1\" target=\"_blank\" rel=\"nofollow noopener\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">VER TESTIMONIOS Y ENTREVISTAS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7416a26 elementor-widget elementor-widget-spacer\" data-id=\"7416a26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-04e7f68 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"04e7f68\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-517cb33\" data-id=\"517cb33\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-15a1e28 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"15a1e28\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-aad2add\" data-id=\"aad2add\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-da9c8e3 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"da9c8e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-size: 30px\">NOTICIAS<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0268fdc elementor-widget elementor-widget-menu-anchor\" data-id=\"0268fdc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"noticias\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9934a05 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"9934a05\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1790752 elementor-invisible\" data-id=\"1790752\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;https:\\\/\\\/globalpartners.cl\\\/corte-de-apelaciones-revierte-fallo-que-ponia-en-riesgo-la-seguridad-laboral-en-la-industria-minera\\\/&quot;,&quot;is_external&quot;:&quot;on&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-element elementor-element-a61b829 caja__testimonios elementor-widget elementor-widget-ha-image-hover-effect happy-addon ha-image-hover-effect\" data-id=\"a61b829\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ha-image-hover-effect.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ha-ihe-wrapper grid\">\n\t\t\t<figure class=\"ha-ihe-fig ha-effect-bubba\">\n\t\t\t\t<img decoding=\"async\" class=\"ha-ihe-img\" src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2025\/05\/sentencia-copia-1.jpg\" alt=\"imagen noticias global partners 4\" title=\"- GLOBAL PARTNERS\">\n\t\t\t\t<figcaption class=\"ha-ihe-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"ha-ihe-title\"><\/h2>\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"ha-ihe-desc\">Corte de Apelaciones revierte fallo que pon\u00eda en riesgo la seguridad laboral en la industria minera <\/br><i class=\"fas fa-search\"><\/i><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;https:\\\/\\\/globalpartners.cl\\\/nueva-politica-nacional-de-seguridad-y-salud-en-el-trabajo-un-paso-clave-para-la-prevencion-del-consumo-de-alcohol-y-drogas-en-empresas\\\/&quot;,&quot;is_external&quot;:&quot;on&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-element elementor-element-8e7f9f1 caja__testimonios elementor-widget elementor-widget-ha-image-hover-effect happy-addon ha-image-hover-effect\" data-id=\"8e7f9f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ha-image-hover-effect.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ha-ihe-wrapper grid\">\n\t\t\t<figure class=\"ha-ihe-fig ha-effect-bubba\">\n\t\t\t\t<img decoding=\"async\" class=\"ha-ihe-img\" src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2024\/07\/getty-images-pU8c_hmwwcU-unsplash-768x474-1.webp\" alt=\"imagen noticias global partners 2\" title=\"- GLOBAL PARTNERS\">\n\t\t\t\t<figcaption class=\"ha-ihe-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"ha-ihe-title\"><\/h3>\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"ha-ihe-desc\">\u00bfSabes lo que dice la nueva pol\u00edtica nacional de seguridad y salud en el trabajo?<\/br><i class=\"fas fa-search\"><\/i><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-62dabbf elementor-invisible\" data-id=\"62dabbf\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;https:\\\/\\\/globalpartners.cl\\\/patricio-labatut-ndasa-2025\\\/&quot;,&quot;is_external&quot;:&quot;on&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-element elementor-element-97eaa4f caja__testimonios elementor-widget elementor-widget-ha-image-hover-effect happy-addon ha-image-hover-effect\" data-id=\"97eaa4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ha-image-hover-effect.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ha-ihe-wrapper grid\">\n\t\t\t<figure class=\"ha-ihe-fig ha-effect-bubba\">\n\t\t\t\t<img decoding=\"async\" class=\"ha-ihe-img\" src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2025\/02\/Patricio-NDASA-Speaker-Badge-copia.webp\" alt=\"imagen noticias global partners 2\" title=\"- GLOBAL PARTNERS\">\n\t\t\t\t<figcaption class=\"ha-ihe-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"ha-ihe-title\"><\/h3>\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"ha-ihe-desc\">\nPatricio Labatut, CEO de Global Partners, ser\u00e1 speaker en la NDASA 2025 Annual Conference &amp; Trade Show<\/br><i class=\"fas fa-search\"><\/i><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;https:\\\/\\\/globalpartners.cl\\\/transporte-casablanca-1ra-empresa-certificada-como-drug-free-workplace\\\/&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-element elementor-element-6008e11 caja__testimonios elementor-widget elementor-widget-ha-image-hover-effect happy-addon ha-image-hover-effect\" data-id=\"6008e11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ha-image-hover-effect.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ha-ihe-wrapper grid\">\n\t\t\t<figure class=\"ha-ihe-fig ha-effect-bubba\">\n\t\t\t\t<img decoding=\"async\" class=\"ha-ihe-img\" src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2023\/09\/imagen-noticias-global-partners-1.webp\" alt=\"imagen noticias global partners 1\" title=\"- GLOBAL PARTNERS\">\n\t\t\t\t<figcaption class=\"ha-ihe-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"ha-ihe-title\"><\/h2>\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"ha-ihe-desc\">Transporte Casablanca: Primera Empresa Certificada como Drug Free Workplace Renueva su Certificaci\u00f3n en Julio de 2024<\/br><i class=\"fas fa-search\"><\/i><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-e16ba38 elementor-invisible\" data-id=\"e16ba38\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;https:\\\/\\\/globalpartners.cl\\\/expectativa-por-sentencia-que-amenaza-seguridad-laboral\\\/&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-element elementor-element-feb2d6e caja__testimonios elementor-widget elementor-widget-ha-image-hover-effect happy-addon ha-image-hover-effect\" data-id=\"feb2d6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ha-image-hover-effect.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ha-ihe-wrapper grid\">\n\t\t\t<figure class=\"ha-ihe-fig ha-effect-bubba\">\n\t\t\t\t<img decoding=\"async\" class=\"ha-ihe-img\" src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2025\/03\/iStock-1440557166-copia-1.webp\" alt=\"imagen noticias global partners 3\" title=\"- GLOBAL PARTNERS\">\n\t\t\t\t<figcaption class=\"ha-ihe-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"ha-ihe-title\"><\/h3>\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"ha-ihe-desc\">Expectativa por sentencia que amenaza seguridad laboral<\/br><i class=\"fas fa-search\"><\/i><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;https:\\\/\\\/globalpartners.cl\\\/cumplimiento-del-nuevo-decreto-ds44-obligaciones-y-soluciones-para-empresas-en-chile\\\/&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-element elementor-element-11f371a caja__testimonios elementor-widget elementor-widget-ha-image-hover-effect happy-addon ha-image-hover-effect\" data-id=\"11f371a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ha-image-hover-effect.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ha-ihe-wrapper grid\">\n\t\t\t<figure class=\"ha-ihe-fig ha-effect-bubba\">\n\t\t\t\t<img decoding=\"async\" class=\"ha-ihe-img\" src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2025\/02\/NL10-2.2-1.jpg\" alt=\"imagen noticias global partners 4\" title=\"- GLOBAL PARTNERS\">\n\t\t\t\t<figcaption class=\"ha-ihe-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"ha-ihe-title\"><\/h2>\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"ha-ihe-desc\">Cumplimiento del nuevo Decreto DS44: Obligaciones y soluciones para empresas en Chile<\/br><i class=\"fas fa-search\"><\/i><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-7da388a elementor-widget elementor-widget-spacer\" data-id=\"7da388a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-861eb8b elementor-align-center btn__verMas__testimonios elementor-invisible elementor-widget elementor-widget-button\" data-id=\"861eb8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/globalpartners.cl\/entrevistas-y-noticias\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"huge huge-news-01\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">CONOCE M\u00c1S CON NUESTRAS ENTREVISTAS Y NOTICIAS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ec2445 elementor-widget elementor-widget-spacer\" data-id=\"2ec2445\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a45ef4c elementor-section-stretched elementor-section-full_width elementor-section-height-min-height elementor-section-content-top elementor-section-items-top elementor-section-height-default\" data-id=\"a45ef4c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;_ha_eqh_enable&quot;:&quot;yes&quot;,&quot;_ha_eqh_widget&quot;:[&quot;image&quot;,&quot;uael-faq&quot;],&quot;_ha_eqh_to&quot;:&quot;widget&quot;,&quot;_ha_eqh_disable_on_tablet&quot;:&quot;no&quot;,&quot;_ha_eqh_disable_on_mobile&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7712ade\" data-id=\"7712ade\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7dbe48e elementor-absolute elementor-invisible elementor-widget elementor-widget-image\" data-id=\"7dbe48e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/06\/female-manager-answering-questions-in-a-work-meeti-2021-08-30-03-50-07-utc-copia-1-768x576.webp\" class=\"attachment-medium_large size-medium_large wp-image-4020\" alt=\"- GLOBAL PARTNERS\" srcset=\"https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/06\/female-manager-answering-questions-in-a-work-meeti-2021-08-30-03-50-07-utc-copia-1-768x576.webp 768w, https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/06\/female-manager-answering-questions-in-a-work-meeti-2021-08-30-03-50-07-utc-copia-1-300x225.webp 300w, https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/06\/female-manager-answering-questions-in-a-work-meeti-2021-08-30-03-50-07-utc-copia-1-16x12.webp 16w, https:\/\/globalpartners.cl\/wp-content\/uploads\/2022\/06\/female-manager-answering-questions-in-a-work-meeti-2021-08-30-03-50-07-utc-copia-1.webp 1000w\" sizes=\"(max-width: 768px) 100vw, 768px\" title=\"- GLOBAL PARTNERS\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5bc5794 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"5bc5794\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PREGUNTAS FRECUENTES<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-27f2ea9 elementor-invisible\" data-id=\"27f2ea9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68f4242 elementor-widget elementor-widget-toggle\" data-id=\"68f4242\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1101\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1101\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-chevron-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u00bfC\u00f3mo afecta el consumo de alcohol y drogas en el trabajo?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1101\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1101\"><p>Las consecuencias del consumo de drogas en el \u00e1mbito laboral tienen un impacto negativo de gran relevancia, tanto para el trabajador como para la organizaci\u00f3n.<\/p><p>Consumir y trabajar bajo la presencia de sustancias psicoactivas en el organismo genera conductas de riesgo, dado que las capacidades mentales y f\u00edsicas del usuario se ven radicalmente afectadas. Esto contribuye a la ocurrencia de accidentes de trabajo, as\u00ed como el aumento del ausentismo, rotaci\u00f3n y disminuci\u00f3n de la productividad de los colaboradores, causados por una baja en el rendimiento y calidad del trabajo.<\/p><p>Algunos otros efectos directos e indirectos que las drogas ocasionan corresponden a:<\/p><ul><li>Aumento progresivo de la cantidad de licencias m\u00e9dicas por patolog\u00edas relacionadas al consumo.<\/li><li>Aparici\u00f3n de alteraciones f\u00edsicas y psicol\u00f3gicas en trabajadores que las consumen.<\/li><li>Incremento de atrasos y faltas injustificadas.<\/li><li>Ansiedad e irritabilidad de los colaboradores que consumen, causadas por abstinencia.<\/li><li>Accidentes que ponen en peligro la vida de los trabajadores y de terceros.<\/li><li>Sobrecarga de trabajo en otros colaboradores por baja del rendimiento del trabajador que consume.<\/li><li>Aumento en los costos de producci\u00f3n ocasionado por bajas de productividad.<\/li><li>Da\u00f1os en equipos y bienes de la empresa.<\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1102\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1102\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-chevron-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u00bfQu\u00e9 tipos de matrices se puede utilizar en los test para la detecci\u00f3n de drogas?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1102\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1102\"><p>Cuando se va a llevar a cabo una prueba de drogas, existe m\u00e1s de una forma de hacerlo. Algunas de ellas son:<\/p><p><strong>En pelo:<\/strong> Para realizar este test, se debe cortar un gramo de cualquier cabello del cuerpo. Esta muestra es enviada a un laboratorio para su an\u00e1lisis, el que utiliza la t\u00e9cnica de cromatograf\u00eda gas o espectrometr\u00eda de masa (GC\/MS)\u201d, entreg\u00e1ndose un resultado cuantitativo por droga. En esta matriz (pelo) se puede detectar si el donante de muestra consumi\u00f3 alguna sustancia psicoactiva en un per\u00edodo estimado de\u00a090 d\u00edas (3 meses) previos a la toma del examen, dependiendo de la zona donde se extraiga el pelo.<\/p><p><strong>En saliva:<\/strong>\u00a0Esta prueba detecta el consumo reciente de drogas y estupefacientes, revelando si fueron consumidos hasta 12 horas antes. Aquello permite obtener un resultado cualitativo inmediato con el uso de un test primario, pudiendo adem\u00e1s entregar uno cuantitativo cuando la muestra es analizada en un laboratorio, utilizando la t\u00e9cnica de cromatograf\u00eda gas o espectrometr\u00eda de masa (GC\/MS).<\/p><p><strong>En orina:<\/strong>\u00a0Permite saber si alguna droga fue usada en promedio 72 horas antes de ser llevado a cabo. Se obtienen resultados cualitativos inmediatos con el uso de un test primario, adem\u00e1s de uno cuantitativo cuando la muestra es analizada en un laboratorio utilizando la misma t\u00e9cnica que los test de saliva y pelo descritos anteriormente.<\/p><p>\u00bfQu\u00e9 tipos de test se pueden realizar para detectar alcohol?<\/p><p>El alcohol puede ser detectado de manera cuantitativa en gramos de alcohol por litro de sangre (gr\/lt), utilizando dispositivos que hacen uso de un flujo de aire expirado. Estos corresponden a equipos electroqu\u00edmicos que preferentemente utilizan la tecnolog\u00eda de celdas de combusti\u00f3n, entregando un resultado num\u00e9rico en gr\/lt o %BAC, de la concentraci\u00f3n equivalente de alcohol en el torrente sangu\u00edneo del donante de la muestra.<\/p><p>Adem\u00e1s, es posible medir los niveles de alcohol cualitativamente, utilizando alcohol\u00edmetros pasivos o test r\u00e1pidos desechables para aliento, saliva u orina, los que reportan un resultado cualitativo (Positivo \/\u00a0 Negativo; Nivel Bajo, Medio o Alto).<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1103\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1103\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-chevron-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u00bfQu\u00e9 tipos de test se pueden realizar para detectar alcohol?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1103\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1103\"><p>El alcohol puede ser detectado de manera cuantitativa en gramos de alcohol por litro de sangre (gr\/lt), utilizando dispositivos que hacen uso de un flujo de aire expirado. Estos corresponden a equipos electroqu\u00edmicos que preferentemente utilizan la tecnolog\u00eda de celdas de combusti\u00f3n, entregando un resultado num\u00e9rico en gr\/lt o %BAC, de la concentraci\u00f3n equivalente de alcohol en el torrente sangu\u00edneo del donante de la muestra.<\/p><p>Adem\u00e1s, es posible medir los niveles de alcohol cualitativamente, utilizando alcohol\u00edmetros pasivos o test r\u00e1pidos desechables para aliento, saliva u orina, los que reportan un resultado cualitativo (Positivo \/\u00a0 Negativo; Nivel Bajo, Medio o Alto).<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1104\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1104\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-chevron-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u00bfCu\u00e1les son los tipos de drogas y qu\u00e9 efectos tienen?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1104\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1104\"><p>Las drogas pueden ser clasificadas de distintas formas seg\u00fan sus efectos en el cuerpo, siendo diferenciadas en categor\u00edas como estimulantes (como anfetaminas, \u00e9xtasis, coca\u00edna y pasta base), depresoras (tales como marihuana, barbit\u00faricos, hipn\u00f3ticos, ansiol\u00edticos y alcohol) y alucin\u00f3genas (peyote y LSD).<\/p><p><strong>THC o Marihuana:<\/strong> Su principio activo es el alucin\u00f3geno llamado tetrahidrocannabinol (THC). Hoy su consumo est\u00e1 socialmente muy normalizado y puede producir efectos como paranoia, da\u00f1os a la capacidad de aprender y a la coordinaci\u00f3n motora, dificultades para realizar tareas complejas, entre otros efectos. Adem\u00e1s, ocasiona una reducci\u00f3n de la atenci\u00f3n y altera la percepci\u00f3n y capacidad de reacci\u00f3n.<\/p><p>El THC est\u00e1 presente en diversas formas, tales como cigarros que com\u00fanmente llevan el nombre de \u201cpitos\u201d o \u201cporros\u201d, galletas, infusiones, aceites, queques o inhalaciones.<\/p><p><strong>Coca\u00edna:<\/strong> Corresponde a un estimulante hecho a partir de hojas de coca, el que se consume en diversas formas, como clorhidrato de coca\u00edna, pasta base o crack. Produce efectos como un aumento de los estados de alerta, mayor energ\u00eda, falta de sue\u00f1o, menor apetito, etc. generando dependencia en un periodo muy corto de tiempo.<\/p><p><strong>Metanfetamina (\u00e9xtasis):<\/strong> Es una droga sint\u00e9tica cuyo efecto es estimulante, siendo el \u00e9xtasis una de sus formas m\u00e1s comunes. Se metaboliza como la anfetamina y puede producir da\u00f1os irreparables al cerebro, manifestados a trav\u00e9s de ataques severos y convulsiones.<\/p><p><strong>PCP o Fenciclidina:<\/strong> Se trata de un alucin\u00f3geno cuyos efectos son impredecibles y variados, los cuales van desde euforia, ansiedad, distorsi\u00f3n del tiempo y del espacio hasta p\u00e1nico o alucinaciones. Esta droga puede conducir a la paranoia y conductas irracionales.<\/p><p><strong>Anfetaminas:<\/strong> Conocidas coloquialmente como \u201cpepas\u201d, estas son estimuladores del sistema nervioso central y pueden causar dependencia severa. Sus efectos incluyen el potenciamiento de los estados de alerta, mayor energ\u00eda, menor apetito o falta de sue\u00f1o. Pueden ser encontradas en algunos medicamentos.<\/p><p><strong>Opi\u00e1ceos:<\/strong> Corresponden a extractos altamente adictivos de una resina de la planta conocida como amapola. Si bien el opio es un alucin\u00f3geno natural, su uso medicinal es analg\u00e9sico dado que deprimen el sistema nervioso central, pudiendo incluso alterar el funcionamiento del sistema respiratorio. Solo se utilizan cl\u00ednicamente en casos de dolores muy severos.<\/p><p><strong>Barbit\u00faricos:<\/strong> Generalmente existen en forma de antidepresivos que producen efectos similares a los del alcohol.<\/p><p><strong>Benzodiacepinas:<\/strong> Son medicamentos psicotr\u00f3picos (es decir, act\u00faan sobre el sistema nervioso central), los que se utilizan terap\u00e9uticamente como relajantes o sedantes para eliminar s\u00edntomas como la ansiedad. Tambi\u00e9n es posible consumirlas como pastillas para dormir.\u00a0<\/p><p><strong>Metadona:<\/strong> Es una droga sint\u00e9tica que produce los mismos efectos que la morfina y hero\u00edna. Se usa principalmente en el tratamiento antidrogas y pueden ser extremadamente adictivas.<\/p><p><strong>Alcohol:<\/strong> Se obtiene a trav\u00e9s de procesos como fermentaci\u00f3n o destilado, cuyo resultado es el etanol. Su consumo est\u00e1 muy normalizado y provoca alteraciones perceptivas, dificulta el procesamiento de informaci\u00f3n y disminuye la concentraci\u00f3n, lo que dificulta la evaluaci\u00f3n de riesgos. Sus s\u00edntomas m\u00e1s frecuentes son euforia, distorsi\u00f3n del habla y perdida de coordinaci\u00f3n motora.<\/p><p><strong>Tabaco:<\/strong> Su nombre proviene de la planta a partir del cual es obtenido, y al igual que el alcohol, es legal. Puede ser altamente adictivo y da\u00f1ino para la salud.<\/p><p>Su consumo est\u00e1 permitido solo en lugares autorizados, de acuerdo a la ley 20.660.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1105\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1105\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-chevron-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u00bfQu\u00e9 drogas son las m\u00e1s consumidas en el trabajo?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1105\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1105\"><p>Nuestro s\u00e9ptimo estudio &#8220;<strong><a href=\"https:\/\/drugfreeworkplace.cl\/estudio-dfwp\/\" rel=\"nofollow noopener\" target=\"_blank\">\u00bfSu empresa da positivo?<\/a><\/strong> Testeo de Alcohol y Drogas en trabajadores Chilenos&#8221;. Se\u00f1ala que la marihuana es el estupefaciente m\u00e1s consumido, con un 9.76% de los resultados respecto a la proporci\u00f3n de positivos al consumo reciente, por tipo de drogas. Le sigue la coca\u00edna con un 7%, mientras que el poli consumo de marihuana y coca\u00edna se encuentra en tercer lugar, con un 4.25%.<\/p><p>Con respecto al alcohol y las metanfetaminas, estas aparecen con un 0,23% y 0,46% respectivamente, mientras que no se registra un consumo positivo de opi\u00e1ceos y anfetaminas.<\/p><p>En cuanto al consumo reciente de estas sustancias por sector de actividad econ\u00f3mica en empresas sin testeos previos, el documento establece que es proporcionalmente mayor en la industria y manufactura, donde un 28.57% de las personas testeadas dio positivo, seguido del sector construcci\u00f3n con un 23.81%. Por su parte, transporte present\u00f3 un 10.62%, comercio un 17.65% y servicios y otros un 18.64%.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1106\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-1106\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-chevron-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u00bfEs legal hacer test de drogas en el trabajo?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1106\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-1106\"><p><span data-contrast=\"auto\">La <a href=\"https:\/\/www.dt.gob.cl\/legislacion\/1624\/w3-article-98159.html\" target=\"_blank\" rel=\"noopener nofollow\"><strong>ORD. N\u00ba3032\/47<\/strong> <\/a><\/span>del departamento jur\u00eddico de la Direcci\u00f3n Nacional del Trabajo, respecto al reglamento interno de una empresa, se\u00f1ala que:<\/p><ol><li>Las obligaciones y prohibiciones que justifican el control en materia de drogas y alcohol debe contenerse en el Reglamento Interno de la empresa.<\/li><li>Las normas relativas al control en materia de drogas y alcohol deben explicitar cu\u00e1l es el procedimiento espec\u00edfico de control empleado en materia de test de drogas y alcohol.<\/li><li>Toda documentaci\u00f3n que se ponga en conocimiento de los trabajadores con relaci\u00f3n al sistema de control del consumo de drogas y de alcohol, debe encontrarse redactado \u00edntegramente en idioma espa\u00f1ol.<\/li><li>Resulta necesario que toda norma relativa al control del consumo de drogas explicite qu\u00e9 tipo de drogas ser\u00e1n objeto de dicho control.<\/li><li>La extensi\u00f3n temporal y territorial de las obligaciones y prohibiciones en materia de consumo de drogas y de abuso de alcohol, debe circunscribirse a las labores, permanencia y vida en las dependencias de la empresa.<\/li><li>Las normas reglamentarias que regulan un programa relativo al control del consumo de drogas y alcohol, deben respetar las exigencias del juicio de proporcionalidad, esto es, deben ser id\u00f3neas, necesarias y proporcionales.<\/li><\/ol><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"\\u00bfC\\u00f3mo afecta el consumo de alcohol y drogas en el trabajo?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Las consecuencias del consumo de drogas en el \\u00e1mbito laboral tienen un impacto negativo de gran relevancia, tanto para el trabajador como para la organizaci\\u00f3n.<\\\/p><p>Consumir y trabajar bajo la presencia de sustancias psicoactivas en el organismo genera conductas de riesgo, dado que las capacidades mentales y f\\u00edsicas del usuario se ven radicalmente afectadas. Esto contribuye a la ocurrencia de accidentes de trabajo, as\\u00ed como el aumento del ausentismo, rotaci\\u00f3n y disminuci\\u00f3n de la productividad de los colaboradores, causados por una baja en el rendimiento y calidad del trabajo.<\\\/p><p>Algunos otros efectos directos e indirectos que las drogas ocasionan corresponden a:<\\\/p><ul><li>Aumento progresivo de la cantidad de licencias m\\u00e9dicas por patolog\\u00edas relacionadas al consumo.<\\\/li><li>Aparici\\u00f3n de alteraciones f\\u00edsicas y psicol\\u00f3gicas en trabajadores que las consumen.<\\\/li><li>Incremento de atrasos y faltas injustificadas.<\\\/li><li>Ansiedad e irritabilidad de los colaboradores que consumen, causadas por abstinencia.<\\\/li><li>Accidentes que ponen en peligro la vida de los trabajadores y de terceros.<\\\/li><li>Sobrecarga de trabajo en otros colaboradores por baja del rendimiento del trabajador que consume.<\\\/li><li>Aumento en los costos de producci\\u00f3n ocasionado por bajas de productividad.<\\\/li><li>Da\\u00f1os en equipos y bienes de la empresa.<\\\/li><\\\/ul>\"}},{\"@type\":\"Question\",\"name\":\"\\u00bfQu\\u00e9 tipos de matrices se puede utilizar en los test para la detecci\\u00f3n de drogas?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Cuando se va a llevar a cabo una prueba de drogas, existe m\\u00e1s de una forma de hacerlo. Algunas de ellas son:<\\\/p><p><strong>En pelo:<\\\/strong> Para realizar este test, se debe cortar un gramo de cualquier cabello del cuerpo. Esta muestra es enviada a un laboratorio para su an\\u00e1lisis, el que utiliza la t\\u00e9cnica de cromatograf\\u00eda gas o espectrometr\\u00eda de masa (GC\\\/MS)\\u201d, entreg\\u00e1ndose un resultado cuantitativo por droga. En esta matriz (pelo) se puede detectar si el donante de muestra consumi\\u00f3 alguna sustancia psicoactiva en un per\\u00edodo estimado de\\u00a090 d\\u00edas (3 meses) previos a la toma del examen, dependiendo de la zona donde se extraiga el pelo.<\\\/p><p><strong>En saliva:<\\\/strong>\\u00a0Esta prueba detecta el consumo reciente de drogas y estupefacientes, revelando si fueron consumidos hasta 12 horas antes. Aquello permite obtener un resultado cualitativo inmediato con el uso de un test primario, pudiendo adem\\u00e1s entregar uno cuantitativo cuando la muestra es analizada en un laboratorio, utilizando la t\\u00e9cnica de cromatograf\\u00eda gas o espectrometr\\u00eda de masa (GC\\\/MS).<\\\/p><p><strong>En orina:<\\\/strong>\\u00a0Permite saber si alguna droga fue usada en promedio 72 horas antes de ser llevado a cabo. Se obtienen resultados cualitativos inmediatos con el uso de un test primario, adem\\u00e1s de uno cuantitativo cuando la muestra es analizada en un laboratorio utilizando la misma t\\u00e9cnica que los test de saliva y pelo descritos anteriormente.<\\\/p><p>\\u00bfQu\\u00e9 tipos de test se pueden realizar para detectar alcohol?<\\\/p><p>El alcohol puede ser detectado de manera cuantitativa en gramos de alcohol por litro de sangre (gr\\\/lt), utilizando dispositivos que hacen uso de un flujo de aire expirado. Estos corresponden a equipos electroqu\\u00edmicos que preferentemente utilizan la tecnolog\\u00eda de celdas de combusti\\u00f3n, entregando un resultado num\\u00e9rico en gr\\\/lt o %BAC, de la concentraci\\u00f3n equivalente de alcohol en el torrente sangu\\u00edneo del donante de la muestra.<\\\/p><p>Adem\\u00e1s, es posible medir los niveles de alcohol cualitativamente, utilizando alcohol\\u00edmetros pasivos o test r\\u00e1pidos desechables para aliento, saliva u orina, los que reportan un resultado cualitativo (Positivo \\\/\\u00a0 Negativo; Nivel Bajo, Medio o Alto).<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"\\u00bfQu\\u00e9 tipos de test se pueden realizar para detectar alcohol?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>El alcohol puede ser detectado de manera cuantitativa en gramos de alcohol por litro de sangre (gr\\\/lt), utilizando dispositivos que hacen uso de un flujo de aire expirado. Estos corresponden a equipos electroqu\\u00edmicos que preferentemente utilizan la tecnolog\\u00eda de celdas de combusti\\u00f3n, entregando un resultado num\\u00e9rico en gr\\\/lt o %BAC, de la concentraci\\u00f3n equivalente de alcohol en el torrente sangu\\u00edneo del donante de la muestra.<\\\/p><p>Adem\\u00e1s, es posible medir los niveles de alcohol cualitativamente, utilizando alcohol\\u00edmetros pasivos o test r\\u00e1pidos desechables para aliento, saliva u orina, los que reportan un resultado cualitativo (Positivo \\\/\\u00a0 Negativo; Nivel Bajo, Medio o Alto).<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"\\u00bfCu\\u00e1les son los tipos de drogas y qu\\u00e9 efectos tienen?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Las drogas pueden ser clasificadas de distintas formas seg\\u00fan sus efectos en el cuerpo, siendo diferenciadas en categor\\u00edas como estimulantes (como anfetaminas, \\u00e9xtasis, coca\\u00edna y pasta base), depresoras (tales como marihuana, barbit\\u00faricos, hipn\\u00f3ticos, ansiol\\u00edticos y alcohol) y alucin\\u00f3genas (peyote y LSD).<\\\/p><p><strong>THC o Marihuana:<\\\/strong> Su principio activo es el alucin\\u00f3geno llamado tetrahidrocannabinol (THC). Hoy su consumo est\\u00e1 socialmente muy normalizado y puede producir efectos como paranoia, da\\u00f1os a la capacidad de aprender y a la coordinaci\\u00f3n motora, dificultades para realizar tareas complejas, entre otros efectos. Adem\\u00e1s, ocasiona una reducci\\u00f3n de la atenci\\u00f3n y altera la percepci\\u00f3n y capacidad de reacci\\u00f3n.<\\\/p><p>El THC est\\u00e1 presente en diversas formas, tales como cigarros que com\\u00fanmente llevan el nombre de \\u201cpitos\\u201d o \\u201cporros\\u201d, galletas, infusiones, aceites, queques o inhalaciones.<\\\/p><p><strong>Coca\\u00edna:<\\\/strong> Corresponde a un estimulante hecho a partir de hojas de coca, el que se consume en diversas formas, como clorhidrato de coca\\u00edna, pasta base o crack. Produce efectos como un aumento de los estados de alerta, mayor energ\\u00eda, falta de sue\\u00f1o, menor apetito, etc. generando dependencia en un periodo muy corto de tiempo.<\\\/p><p><strong>Metanfetamina (\\u00e9xtasis):<\\\/strong> Es una droga sint\\u00e9tica cuyo efecto es estimulante, siendo el \\u00e9xtasis una de sus formas m\\u00e1s comunes. Se metaboliza como la anfetamina y puede producir da\\u00f1os irreparables al cerebro, manifestados a trav\\u00e9s de ataques severos y convulsiones.<\\\/p><p><strong>PCP o Fenciclidina:<\\\/strong> Se trata de un alucin\\u00f3geno cuyos efectos son impredecibles y variados, los cuales van desde euforia, ansiedad, distorsi\\u00f3n del tiempo y del espacio hasta p\\u00e1nico o alucinaciones. Esta droga puede conducir a la paranoia y conductas irracionales.<\\\/p><p><strong>Anfetaminas:<\\\/strong> Conocidas coloquialmente como \\u201cpepas\\u201d, estas son estimuladores del sistema nervioso central y pueden causar dependencia severa. Sus efectos incluyen el potenciamiento de los estados de alerta, mayor energ\\u00eda, menor apetito o falta de sue\\u00f1o. Pueden ser encontradas en algunos medicamentos.<\\\/p><p><strong>Opi\\u00e1ceos:<\\\/strong> Corresponden a extractos altamente adictivos de una resina de la planta conocida como amapola. Si bien el opio es un alucin\\u00f3geno natural, su uso medicinal es analg\\u00e9sico dado que deprimen el sistema nervioso central, pudiendo incluso alterar el funcionamiento del sistema respiratorio. Solo se utilizan cl\\u00ednicamente en casos de dolores muy severos.<\\\/p><p><strong>Barbit\\u00faricos:<\\\/strong> Generalmente existen en forma de antidepresivos que producen efectos similares a los del alcohol.<\\\/p><p><strong>Benzodiacepinas:<\\\/strong> Son medicamentos psicotr\\u00f3picos (es decir, act\\u00faan sobre el sistema nervioso central), los que se utilizan terap\\u00e9uticamente como relajantes o sedantes para eliminar s\\u00edntomas como la ansiedad. Tambi\\u00e9n es posible consumirlas como pastillas para dormir.\\u00a0<\\\/p><p><strong>Metadona:<\\\/strong> Es una droga sint\\u00e9tica que produce los mismos efectos que la morfina y hero\\u00edna. Se usa principalmente en el tratamiento antidrogas y pueden ser extremadamente adictivas.<\\\/p><p><strong>Alcohol:<\\\/strong> Se obtiene a trav\\u00e9s de procesos como fermentaci\\u00f3n o destilado, cuyo resultado es el etanol. Su consumo est\\u00e1 muy normalizado y provoca alteraciones perceptivas, dificulta el procesamiento de informaci\\u00f3n y disminuye la concentraci\\u00f3n, lo que dificulta la evaluaci\\u00f3n de riesgos. Sus s\\u00edntomas m\\u00e1s frecuentes son euforia, distorsi\\u00f3n del habla y perdida de coordinaci\\u00f3n motora.<\\\/p><p><strong>Tabaco:<\\\/strong> Su nombre proviene de la planta a partir del cual es obtenido, y al igual que el alcohol, es legal. Puede ser altamente adictivo y da\\u00f1ino para la salud.<\\\/p><p>Su consumo est\\u00e1 permitido solo en lugares autorizados, de acuerdo a la ley 20.660.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"\\u00bfQu\\u00e9 drogas son las m\\u00e1s consumidas en el trabajo?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Nuestro s\\u00e9ptimo estudio &#8220;<strong><a href=\\\"https:\\\/\\\/drugfreeworkplace.cl\\\/estudio-dfwp\\\/\\\">\\u00bfSu empresa da positivo?<\\\/a><\\\/strong> Testeo de Alcohol y Drogas en trabajadores Chilenos&#8221;. Se\\u00f1ala que la marihuana es el estupefaciente m\\u00e1s consumido, con un 9.76% de los resultados respecto a la proporci\\u00f3n de positivos al consumo reciente, por tipo de drogas. Le sigue la coca\\u00edna con un 7%, mientras que el poli consumo de marihuana y coca\\u00edna se encuentra en tercer lugar, con un 4.25%.<\\\/p><p>Con respecto al alcohol y las metanfetaminas, estas aparecen con un 0,23% y 0,46% respectivamente, mientras que no se registra un consumo positivo de opi\\u00e1ceos y anfetaminas.<\\\/p><p>En cuanto al consumo reciente de estas sustancias por sector de actividad econ\\u00f3mica en empresas sin testeos previos, el documento establece que es proporcionalmente mayor en la industria y manufactura, donde un 28.57% de las personas testeadas dio positivo, seguido del sector construcci\\u00f3n con un 23.81%. Por su parte, transporte present\\u00f3 un 10.62%, comercio un 17.65% y servicios y otros un 18.64%.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"\\u00bfEs legal hacer test de drogas en el trabajo?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p><span data-contrast=\\\"auto\\\">La <a href=\\\"https:\\\/\\\/www.dt.gob.cl\\\/legislacion\\\/1624\\\/w3-article-98159.html\\\" target=\\\"_blank\\\" rel=\\\"noopener\\\"><strong>ORD. N\\u00ba3032\\\/47<\\\/strong> <\\\/a><\\\/span>del departamento jur\\u00eddico de la Direcci\\u00f3n Nacional del Trabajo, respecto al reglamento interno de una empresa, se\\u00f1ala que:<\\\/p><ol><li>Las obligaciones y prohibiciones que justifican el control en materia de drogas y alcohol debe contenerse en el Reglamento Interno de la empresa.<\\\/li><li>Las normas relativas al control en materia de drogas y alcohol deben explicitar cu\\u00e1l es el procedimiento espec\\u00edfico de control empleado en materia de test de drogas y alcohol.<\\\/li><li>Toda documentaci\\u00f3n que se ponga en conocimiento de los trabajadores con relaci\\u00f3n al sistema de control del consumo de drogas y de alcohol, debe encontrarse redactado \\u00edntegramente en idioma espa\\u00f1ol.<\\\/li><li>Resulta necesario que toda norma relativa al control del consumo de drogas explicite qu\\u00e9 tipo de drogas ser\\u00e1n objeto de dicho control.<\\\/li><li>La extensi\\u00f3n temporal y territorial de las obligaciones y prohibiciones en materia de consumo de drogas y de abuso de alcohol, debe circunscribirse a las labores, permanencia y vida en las dependencias de la empresa.<\\\/li><li>Las normas reglamentarias que regulan un programa relativo al control del consumo de drogas y alcohol, deben respetar las exigencias del juicio de proporcionalidad, esto es, deben ser id\\u00f3neas, necesarias y proporcionales.<\\\/li><\\\/ol>\"}}]}<\/script>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a7a8c30 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a7a8c30\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9e0421b\" data-id=\"9e0421b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b6b3eb elementor-align-center btn__verMas__testimonios elementor-invisible elementor-widget elementor-widget-button\" data-id=\"4b6b3eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/globalpartners.cl\/#contacto\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">CON\u00c9CTATE CON NOSOTROS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-93ad6e8\" data-id=\"93ad6e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1eb6246 elementor-align-left btn__verMas__testimonios elementor-invisible elementor-widget elementor-widget-button\" data-id=\"1eb6246\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/wa.me\/56963961668\" target=\"_blank\" rel=\"nofollow noopener\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">LL\u00c1MANOS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Proteger la vida y salud de los trabajadores es nuestro prop\u00f3sito Desliza NUESTROS CLIENTES SE PARTE DE GLOBAL PARTNERS DIVISI\u00d3NALCOHOL Y DROGAS Programa Drug Free Workplace El programa DFWP es un aporte metodol\u00f3gico para que las empresas puedan abordar con \u00e9xito la problem\u00e1tica del consumo de alcohol y drogas en ambientes laborales. SABER M\u00c1S > [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":5140,"parent":0,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_joinchat":[],"footnotes":""},"class_list":["post-6416","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/globalpartners.cl\/en\/wp-json\/wp\/v2\/pages\/6416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globalpartners.cl\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/globalpartners.cl\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/globalpartners.cl\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/globalpartners.cl\/en\/wp-json\/wp\/v2\/comments?post=6416"}],"version-history":[{"count":22,"href":"https:\/\/globalpartners.cl\/en\/wp-json\/wp\/v2\/pages\/6416\/revisions"}],"predecessor-version":[{"id":7281,"href":"https:\/\/globalpartners.cl\/en\/wp-json\/wp\/v2\/pages\/6416\/revisions\/7281"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalpartners.cl\/en\/wp-json\/wp\/v2\/media\/5140"}],"wp:attachment":[{"href":"https:\/\/globalpartners.cl\/en\/wp-json\/wp\/v2\/media?parent=6416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}